{"id":324,"date":"2019-05-22T10:27:49","date_gmt":"2019-05-22T13:27:49","guid":{"rendered":"http:\/\/deborarufino.com.br\/blog\/?p=324"},"modified":"2021-07-23T09:26:05","modified_gmt":"2021-07-23T12:26:05","slug":"profissional-do-direito","status":"publish","type":"post","link":"http:\/\/deborarufino.com.br\/blog\/profissional-do-direito\/","title":{"rendered":"Profissional do Direito"},"content":{"rendered":"<h1 style=\"text-align: center;\"><strong><span style=\"color: #ff6600;\">Profissional do Direito<\/span><\/strong><\/h1>\n<h3><\/h3>\n<h3 style=\"text-align: center;\"><span style=\"font-family: helvetica, arial, sans-serif; color: #ff9900;\"><strong>O Advogado precisa ter um perfil adequado para a \u00e1rea que deseja atuar, e isso n\u00e3o diz respeito apenas a gradua\u00e7\u00e3o.<\/strong><\/span><\/h3>\n<p>&nbsp;<\/p>\n<p>Profissional do Direito est\u00e1 em uma das mais antigas profiss\u00f5es do mundo. Pois, o Direito exerce grande fasc\u00ednio nos jovens porque cuida, essencialmente, da organiza\u00e7\u00e3o social.<\/p>\n<p>O Direito \u00e9 din\u00e2mico, acompanha as mudan\u00e7as, hoje muito aceleradas, da realidade. Por isso, sua pratica exige estudo constante, muita leitura, cultura geral aprofundada, coordena\u00e7\u00e3o de ideias, habilidades de argumenta\u00e7\u00e3o, capacidade de convencimento e poder de an\u00e1lise.<\/p>\n<p>O profissional do Direito que conclui o curdo de gradua\u00e7\u00e3o, tem, a seu dispor uma ampla e variada gama de op\u00e7\u00f5es, ou seja, perspectivas profissionais dentro da carreira jur\u00eddica.<\/p>\n<p>&nbsp;<\/p>\n<h2><span style=\"color: #ff6600;\"><strong>Especializa\u00e7\u00e3o na Advocacia<\/strong><\/span><\/h2>\n<p>As especializa\u00e7\u00f5es s\u00e3o variadas, da mesma forma, muitas s\u00e3o \u00e1reas de atua\u00e7\u00e3o. Entre os ramos mais promissores h\u00e1 tradicionais como:<\/p>\n<ul>\n<li>Direito Tribut\u00e1rio \u2013 Planejamento, auditorias, aquisi\u00e7\u00f5es, fus\u00f5es e reorganiza\u00e7\u00e3o societ\u00e1rios nas empresas;<\/li>\n<li>Direito Criminal;<\/li>\n<li>Direito Civil \u2013 Fam\u00edlia, heran\u00e7a, sucess\u00f5es, propriedade;<\/li>\n<li>Direito Trabalhista;<\/li>\n<li>Direito Previdenci\u00e1rio.<\/li>\n<\/ul>\n<p>E at\u00e9 os mais recentes:<\/p>\n<ul>\n<li>Direito Eletr\u00f4nico;<\/li>\n<li>Direito do Consumidor, que entrou em vigor com o <a href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/leis\/l8078.htm\">C\u00f3digo de Defesa do Consumidor<\/a>;<\/li>\n<li>Direito Internacional, que se expandiu com a globaliza\u00e7\u00e3o, pois as rela\u00e7\u00f5es entre os pa\u00edses passaram a exigir leis reguladoras do com\u00e9rcio internacional;<\/li>\n<li>Direito Ambiental, devido a preocupa\u00e7\u00e3o mundial com o meio ambiente, o aquecimento global e o desmatamento.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2><strong><span style=\"color: #ff6600;\">Advogado pode trabalhar como?<img data-attachment-id=\"333\" data-permalink=\"http:\/\/deborarufino.com.br\/blog\/profissional-do-direito\/profisisonal-advogado\/\" data-orig-file=\"https:\/\/i0.wp.com\/deborarufino.com.br\/blog\/wp-content\/uploads\/2019\/05\/profisisonal-advogado.jpeg?fit=291%2C173\" data-orig-size=\"291,173\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"profisisonal advogado\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/deborarufino.com.br\/blog\/wp-content\/uploads\/2019\/05\/profisisonal-advogado.jpeg?fit=291%2C173\" data-large-file=\"https:\/\/i0.wp.com\/deborarufino.com.br\/blog\/wp-content\/uploads\/2019\/05\/profisisonal-advogado.jpeg?fit=291%2C173\" loading=\"lazy\" class=\"alignnone size-full wp-image-333 alignright\" src=\"https:\/\/i0.wp.com\/deborarufino.com.br\/blog\/wp-content\/uploads\/2019\/05\/profisisonal-advogado.jpeg?resize=291%2C173\" alt=\"\" width=\"291\" height=\"173\" data-recalc-dims=\"1\" \/><\/span><\/strong><\/h2>\n<p>O profissional do Direito, como advogado pode trabalhar em assessorias ou consultorias jur\u00eddicas de \u00f3rg\u00e3o do governo, como destaque para empresas privadas, ou tamb\u00e9m, tornar-se um profissional aut\u00f4nomo.<\/p>\n<p>O profissional do Direito ainda pode ser, al\u00e9m de advogado, delegado de policia (Civil e Federal), juiz de Direito (Estadual ou Federal), procurador da Republica dos Estados e dos Munic\u00edpios, promotor p\u00fablico (Estadual ou Federal), assistente jur\u00eddico e assessor jur\u00eddico em \u00f3rg\u00e3os p\u00fablicos e de institui\u00e7\u00f5es privadas.<\/p>\n<p>Al\u00e9m disso, podendo ainda desempenhar a carreira acad\u00eamica, como professor universit\u00e1rio e escritor de obras jur\u00eddicas (doutrinadores) al\u00e9m de estar habilitado para prestar os demais concursos p\u00fablicos que exigem os cursos jur\u00eddicos de gradua\u00e7\u00e3o.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong><span style=\"color: #ff6600;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Perfil do Profissional formado em Direito<\/span><\/span><\/span><\/strong><\/h2>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">O profissional do Direito poderia ser definido como um administrador de conflitos que luta para que as pessoas tenham seus direitos de cidad\u00e3os preservados.<\/span><\/span><\/p>\n<p>Em primeiro lugar, a dedica\u00e7\u00e3o, o estudo constante e a sensibilidade humana e social s\u00e3o tra\u00e7os marcantes na vida deste profissional.<\/p>\n<p>Al\u00e9m disso, s\u00e3o fundamentais a disposi\u00e7\u00e3o para ler e possuir habilidades e redigir e falar em atos p\u00fablicos.<\/p>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">O profissional do Direito \u00e9 aquele conhecedor de sua realidade e de sua import\u00e2ncia para o meio onde atua. \u00c9 o conhecedor da hist\u00f3ria como fen\u00f4meno que viabiliza novas gera\u00e7\u00f5es. Numa perfeita intera\u00e7\u00e3o dos conhecimentos em busca da liberdade, da paz e da justi\u00e7a.<\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><strong><span style=\"color: #ff6600;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><img data-attachment-id=\"335\" data-permalink=\"http:\/\/deborarufino.com.br\/blog\/profissional-do-direito\/planejamento-incial-na-advocacia-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/deborarufino.com.br\/blog\/wp-content\/uploads\/2019\/05\/Planejamento-Incial-na-Advocacia-1.jpg?fit=300%2C300\" data-orig-size=\"300,300\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Planejamento Incial na Advocacia\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/deborarufino.com.br\/blog\/wp-content\/uploads\/2019\/05\/Planejamento-Incial-na-Advocacia-1.jpg?fit=300%2C300\" data-large-file=\"https:\/\/i0.wp.com\/deborarufino.com.br\/blog\/wp-content\/uploads\/2019\/05\/Planejamento-Incial-na-Advocacia-1.jpg?fit=300%2C300\" loading=\"lazy\" class=\"alignnone size-full wp-image-335 alignleft\" src=\"https:\/\/i0.wp.com\/deborarufino.com.br\/blog\/wp-content\/uploads\/2019\/05\/Planejamento-Incial-na-Advocacia-1.jpg?resize=300%2C300\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/i0.wp.com\/deborarufino.com.br\/blog\/wp-content\/uploads\/2019\/05\/Planejamento-Incial-na-Advocacia-1.jpg?w=300 300w, https:\/\/i0.wp.com\/deborarufino.com.br\/blog\/wp-content\/uploads\/2019\/05\/Planejamento-Incial-na-Advocacia-1.jpg?resize=150%2C150 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" data-recalc-dims=\"1\" \/>Planejamento Inicial na Advocacia<\/span><\/span><\/span><\/strong><\/h2>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Pr\u00f3ximo passo ap\u00f3s conhecer o Perfil do Advogado \u00e9 preparar o Planejamento Inicial.<\/span><\/span><\/p>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Planejamento Inicial na Advocacia come\u00e7a em uma prepara\u00e7\u00e3o bem antes de receber t\u00e3o querida carteira da Ordem, o diploma ou mesmo a apresenta\u00e7\u00e3o do TCC.<\/span><\/span><\/p>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">O Planejamento para a advocacia ocorre desde nos bancos da faculdade. Com a escolha do curso que cursar\u00e1, bem como os est\u00e1gios que se submeter\u00e1.<\/span><\/span><\/p>\n<p><a href=\"http:\/\/deborarufino.com.br\/blog\/planejamento-inicial-na-advocacia\/\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Saiba mais sobre como fazer o Planejamento Inicial na Advocacia.<\/span><\/span><\/a><\/p>\n<p>Est\u00e1 precisando de uma orienta\u00e7\u00e3o? Converse com um <a href=\"http:\/\/deborarufino.com.br\/blog\/contabilidade-para-advogados\/\">contador especializado em Advogados<\/a>. Ele saber\u00e1 lhe orientar para uma melhor decis\u00e3o. <a href=\"http:\/\/deborarufino.com.br\/blog\/contabilidade-para-advogados\/\">Saiba como<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ff6600;\"><em><strong>FA\u00c7A PARTE DA NOSSA NEWLESTER<\/strong><\/em><\/span><\/p>\n<p>&nbsp;<\/p>\n<div id='contact-form-324'>\n<form action='http:\/\/deborarufino.com.br\/blog\/profissional-do-direito\/#contact-form-324' method='post' class='contact-form commentsblock'>\n\n<div class='grunion-field-wrap grunion-field-name-wrap'  >\n<label \n\t\t\t\tfor='g324-nome' \n\t\t\t\tclass='grunion-field-label name'\n\t\t\t\t>Nome<span>(obrigat\u00f3rio)<\/span><\/label>\n<input \n\t\t\t\t\ttype='text' \n\t\t\t\t\tname='g324-nome' \n\t\t\t\t\tid='g324-nome' \n\t\t\t\t\tvalue='' \n\t\t\t\t\tclass='name'  \n\t\t\t\t\trequired aria-required='true' \n\t\t\t\t\/>\n\t<\/div>\n\n<div class='grunion-field-wrap grunion-field-email-wrap'  >\n<label \n\t\t\t\tfor='g324-email' \n\t\t\t\tclass='grunion-field-label email'\n\t\t\t\t>E-mail<span>(obrigat\u00f3rio)<\/span><\/label>\n<input \n\t\t\t\t\ttype='email' \n\t\t\t\t\tname='g324-email' \n\t\t\t\t\tid='g324-email' \n\t\t\t\t\tvalue='' \n\t\t\t\t\tclass='email'  \n\t\t\t\t\trequired aria-required='true' \n\t\t\t\t\/>\n\t<\/div>\n\n<div class='grunion-field-wrap grunion-field-textarea-wrap'  >\n<label \n\t\t\t\tfor='contact-form-comment-g324-mensagem' \n\t\t\t\tclass='grunion-field-label textarea'\n\t\t\t\t>Mensagem<\/label>\n<textarea\n\t\t                name='g324-mensagem' \n\t\t                id='contact-form-comment-g324-mensagem' \n\t\t                rows='20' class='textarea'  ><\/textarea>\n\t<\/div>\n\t<p class='contact-submit'>\n\t\t<input type='submit' value='Enviar' class='pushbutton-wide'\/>\n\t\t<input type='hidden' name='contact-form-id' value='324' \/>\n\t\t<input type='hidden' name='action' value='grunion-contact-form' \/>\n\t\t<input type='hidden' name='contact-form-hash' value='a684ec9b0020084800dec463d9d8b64d7418ab50' \/>\n\t<\/p>\n<\/form>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Profissional do Direito O Advogado precisa ter um perfil adequado para a \u00e1rea que deseja atuar, e isso n\u00e3o diz respeito apenas a gradua\u00e7\u00e3o. &nbsp; Profissional do Direito est\u00e1 em uma das mais antigas profiss\u00f5es do mundo. Pois, o Direito exerce grande fasc\u00ednio nos jovens porque cuida, essencialmente, da organiza\u00e7\u00e3o social. O Direito \u00e9 din\u00e2mico, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":326,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"sharing_disabled":false,"spay_email":"","jetpack_publicize_message":""},"categories":[45],"tags":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/deborarufino.com.br\/blog\/wp-content\/uploads\/2019\/05\/profissional-do-direito.jpg?fit=300%2C250","jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/payWIZ-5e","jetpack-related-posts":[],"_links":{"self":[{"href":"http:\/\/deborarufino.com.br\/blog\/wp-json\/wp\/v2\/posts\/324"}],"collection":[{"href":"http:\/\/deborarufino.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/deborarufino.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/deborarufino.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/deborarufino.com.br\/blog\/wp-json\/wp\/v2\/comments?post=324"}],"version-history":[{"count":11,"href":"http:\/\/deborarufino.com.br\/blog\/wp-json\/wp\/v2\/posts\/324\/revisions"}],"predecessor-version":[{"id":1496,"href":"http:\/\/deborarufino.com.br\/blog\/wp-json\/wp\/v2\/posts\/324\/revisions\/1496"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/deborarufino.com.br\/blog\/wp-json\/wp\/v2\/media\/326"}],"wp:attachment":[{"href":"http:\/\/deborarufino.com.br\/blog\/wp-json\/wp\/v2\/media?parent=324"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/deborarufino.com.br\/blog\/wp-json\/wp\/v2\/categories?post=324"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/deborarufino.com.br\/blog\/wp-json\/wp\/v2\/tags?post=324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}